{"text_format":"1","workbook":"xlsx","n_sheets":10,"sheets":["Instructions","Section 1","Section 2","Section 3","Section 4","Summary","Checks","OutputForCSV","Lists","TempOutput"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":0,"defined_names":49,"comments":7,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Instructions","index":0,"n_rows":19,"n_cols":3,"rows_kept":19,"cut":false,"hidden":false,"merged":[]}
[]
[null,null,"OMB Control Number: 2060-0170"]
[null,null,"Expiration Date: 4/30/2023"]
[null,null,"U.S. Environmental Protection Agency "]
[null,null,"Stratospheric Ozone Protection Program"]
[]
[null,null,"Methyl Bromide Producer Quarterly Report (Sec 82.13)"]
[null,null,"Version 4.1"]
[null,null,"Last Updated: July 2020"]
[]
[null,null,"Instructions"]
[null,null,"Complete this form by filling in the data fields that are highlighted in blue.  Guidance on how to complete individual data fields are provided in comment bubbles. Use the arrows to navigate between the tabs. Once completed, use the 'prepare submission' button on the Summary tab to generate your CSV file.  "]
[null,null,"Report Submission: This Excel file, the generated CSV file, and all supporting attachments should be submitted to EPA through the Central Data Exchange (CDX). Refer to EPA's website for additional information on form submission:"]
[null,null,"https://www.epa.gov/ods-phaseout/ods-recordkeeping-and-reporting"]
[]
[null,null,"All information submitted to EPA will be treated as confidential in accordance with 40 CFR Part 2, Subpart B, and will only be disclosed by the means set forth in the subpart. "]
[null,null,"This collection of information is approved by OMB under the Paperwork Reduction Act, 44 U.S.C. 3501 et seq. (OMB Control No. 2060-0170). Responses to this collection of information are mandatory (40 CFR 82.13). An agency may not conduct or sponsor, and a person is not required to respond to, a collection of information unless it displays a currently valid OMB control number. The number and expiration date are displayed in the upper right corner of the form. The public reporting and recordkeeping burden for this collection of information is estimated to be 1 hour per response. Send comments on the Agency’s need this formation, the accuracy of the provided burden estimates and any suggested methods for minimizing respondent burden including through the use of automated collection techniques to the Director, Regulatory Support Division, U.S. Environmental Protection Agency (2821T), 1200 Pennsylvania Ave., NW, Washington, D.C. 20460.  Include the OMB control number in any correspondence.  Do not send the completed form to this address."]
[]
[null,null,"EPA Form #5900-141"]

{"sheet":"Section 1","index":1,"n_rows":15,"n_cols":9,"rows_kept":15,"cut":false,"hidden":false,"merged":[[7,2,7,3]]}
[]
[null,null,"U.S. Environmental Protection Agency"]
[null,null,"Methyl Bromide Producer Quarterly Report"]
[]
[null,null,"   Date Prepared:",{"$f":"TODAY()","v":"2020-07-15"}]
[]
[null,null,"Section 1: Report Identification Information "]
[null,null,"Complete all fields below.  No fields may be left blank."]
[null,null,"Company Name: ",null,null,{"$f":"IF($D$9=0,1,0)","v":1}]
[null,null,"Submission Type:",null,null,{"$f":"IF(OR(SubTSelection=Lists!C3,SubTSelection=Lists!C4),0,1)","v":1},null,null,{"$f":"IF(SubTSelection=\"\",\"\",IF(OR(SubTSelection=Lists!C3,SubTSelection=Lists!C4),\"\",\"PLEASE SELECT A VALID SUBMISSION TYPE FROM THE DROPDOWN LIST\"))","v":""}]
[null,null,"Reporting Year:",null,null,{"$f":"IF(OR($D$11=0,$D$11>Lists!$E$3),1,0)","v":1},null,null,{"$f":"IF(D11>Lists!E3,\"PLEASE CHOOSE A CURRENT OR PAST YEAR\",\"\")","v":""}]
[null,null,"Reporting Quarter:",null,null,{"$f":"IF(OR(ReportQtr=0,ReportQtr>Lists!F6),1,0)","v":1},null,null,{"$f":"IF(ReportQtr>Lists!F6,\"PLEASE SELECT A VALID QUARTER FROM THE DROPDOWN LIST\",\"\")","v":""}]
[null,null,null,""]
[null,null,null,{"$f":"Lists!C3","v":"Original Submission"}]
[null,null,null,{"$f":"Lists!C4","v":"Re-Submittal"}]

{"sheet":"Section 2","index":2,"n_rows":13,"n_cols":20,"rows_kept":13,"cut":false,"hidden":false,"merged":[[8,3,8,13],[18,3,18,4],[13,3,13,4],[14,3,14,4],[15,3,15,4],[16,3,16,4],[17,3,17,4]]}
[]
[null,null,null,"U.S. Environmental Protection Agency"]
[null,null,null,"Methyl Bromide Producer Quarterly Report"]
[]
[null,null,null,"Company Name:",{"$f":"IF('Section 1'!D9=0,\"\",'Section 1'!D9)","v":""}]
[null,null,null,"Reporting Period:",{"$f":"IF(OR('Section 1'!D11=0,'Section 1'!D12=0),\"\",\"Quarter \"&'Section 1'!D12&\", \"&'Section 1'!D11)","v":""}]
[]
[null,null,null,"Section 2: Production Data"]
[null,null,null,"In the table below, enter the quantity of methyl bromide that was produced during the reporting period.  If no methyl bromide was produced, the table may be left blank. As a reminder, if methyl bromide was produced for QPS applications, global lab, emergency uses, second party transformation, or second party destruction, a copy of the transformation verification, destruction verification, QPS certification, and/or essential use certification from each company for whom material was produced must be provided to EPA along with the submission of this report.\n"]
[null,null,null,"In-House Transformation ","Second Party Transformation ","In-House Destruction ","Second Party Destruction ","QPS","Pre-Plant Critical Use","Post-Harvest Critical Use","Critical Use for Export","Emergency Use","Global Lab","Gross Production"]
[null,null,null,"kg","kg","kg","kg","kg","kg","kg","kg","kg","kg","Autopopulated"]
[null,null,null,1500,0,0,0,100.5,0,200,0,0,0,{"$f":"D12+E12+F12+G12+H12+I12+J12+K12+L12+M12","v":1800.5},null,null,"Filled Out?","Sec2 Inclusion 2nd Party in Sec 3? - Trans/Dest","Section 3 Inclusion - Global Lab/Emergency","NegNumber?"]
[{"$f":"IF(Q13=0,1,\"\")","v":""},null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF((D13+E13+F13+G13+H13+I13+J13+K13+L13+M13)=0,\"\",D13+E13+F13+G13+H13+I13+J13+K13+L13+M13)","v":""},null,null,{"$f":"IF(N13=\"\",\"N\",0)","v":"N"},{"$f":"IF(Q13=\"N\",0,IF(OR(AND(E13>0,COUNTIF('Section 3'!$G$15:$G$50,Lists!G3)=0),AND(G13>0,COUNTIF('Section 3'!$G$15:$G$50,Lists!G4)=0),AND(H13>0,COUNTIF('Section 3'!$G$15:$G$50,Lists!G5)=0)),1,0))","v":0},{"$f":"IF(Q13=\"N\",0,IF(OR(AND(M13>0,COUNTIF('Section 3'!$G$15:$G$50,Lists!G6)=0),AND(L13>0,COUNTIF('Section 3'!$G$15:$G$50,Lists!G7)=0)),1,0))","v":0},{"$f":"IF(OR(D13<0,E13<0,F13<0,G13<0,H13<0,K13<0,L13<0,M13<0),1,0)","v":0}]

{"sheet":"Section 3","index":3,"n_rows":56,"n_cols":18,"rows_kept":56,"cut":false,"hidden":false,"merged":[[23,3,23,4],[18,3,18,4],[19,3,19,4],[20,3,20,4],[21,3,21,4],[22,3,22,4],[13,3,13,4],[14,3,14,4],[15,3,15,4],[16,3,16,4],[17,3,17,4],[8,3,8,6],[9,3,9,6],[10,3,10,6],[11,3,11,4],[12,3,12,4],[24,3,24,4],[25,3,25,4],[26,3,26,4],[27,3,27,4],[28,3,28,4],[29,3,29,4],[30,3,30,4],[31,3,31,4],[32,3,32,4],[33,3,33,4],[34,3,34,4],[35,3,35,4],[36,3,36,4],[37,3,37,4],[38,3,38,4],[39,3,39,4],[40,3,40,4],[41,3,41,4],[42,3,42,4],[43,3,43,4],[49,3,49,4],[44,3,44,4],[45,3,45,4],[46,3,46,4],[47,3,47,4],[48,3,48,4]]}
[]
[null,null,null,"U.S. Environmental Protection Agency"]
[null,null,null,"Methyl Bromide Producer Quarterly Report"]
[]
[null,null,null,"Company Name:",{"$f":"IF('Section 1'!D9=0,\"\",'Section 1'!D9)","v":""}]
[null,null,null,"Reporting Period:",{"$f":"IF(OR('Section 1'!D11=0,'Section 1'!D12=0),\"\",\"Quarter \"&'Section 1'!D12&\", \"&'Section 1'!D11)","v":""}]
[]
[null,null,null,"Section 3: Shipment/Sales Data"]
[null,null,null,"Identify the recipient company(s) of the methyl bromide produced for second party transformation, second party destruction, QPS, global lab, and/or emergency uses, and the amount shipped to or purchased by each recipient company during the quarter. "]
[null,null,null,"Note: Due to a potential time lag between the date of production and the date of shipment, it is recognized that for a given quarter the information in Section 3 may not match the information reported in Section 2 for second party transformation, second party destruction, and QPS; however, it is expected that all material produced for second party transformation, second party destruction, and QPS will eventually be shipped to a second party and must be reported as such in the applicable quarterly report. "]
[null,null,null,"As a reminder, a copy of the transformation verification, destruction verification, QPS certification, and/or essential use certification from each second party for whom material was produced must be provided to EPA along with the submission of this report."]
[null,null,null,"Recipient Company Name",null,"Quantity","Purpose"]
[null,null,null,"Text",null,"kg","Selection"]
[null,null,null,"Company A",null,10,"Transformation",null,null,null,null,"ActiveRow?","Character Check","Completeness check","Valid Purpose","Sec2 Inclusion in Sec3 - LE","Sec2 Inclusion in Sec3 - 2nd Party/QPS","NegNumber?"]
[{"$f":"IF(D15=0,\"\",1)","v":""},null,null,null,null,null,null,null,null,null,null,{"$f":"IF(A15=\"\",\"N\",\"Y\")","v":"N"},{"$f":"IF(LEN(D15)>200,1,0)","v":0},{"$f":"IF(D15=0,0,IF(OR(F15=0,G15=0),1,0))","v":0},{"$f":"IF(G15=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G15)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G15=Lists!$G$6),AND('Section 2'!$L$13=0,G15=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G15=Lists!$G$3),AND('Section 2'!$G$13=0,G15=Lists!$G$4),AND('Section 2'!$H$13=0,G15=Lists!$G$5)),1,0)","v":0},{"$f":"IF(F15<0,1,0)","v":0}]
[{"$f":"IF(D16=0,\"\",MAX($A$15:A15)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",{"$f":"IF(LEN(D16)>200,1,0)","v":0},{"$f":"IF(D16=0,0,IF(OR(F16=0,G16=0),1,0))","v":0},{"$f":"IF(G16=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G16)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G16=Lists!$G$6),AND('Section 2'!$L$13=0,G16=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G16=Lists!$G$3),AND('Section 2'!$G$13=0,G16=Lists!$G$4),AND('Section 2'!$H$13=0,G16=Lists!$G$5)),1,0)","v":0},{"$f":"IF(F16<0,1,0)","v":0}]
[{"$f":"IF(D17=0,\"\",MAX($A$15:A16)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,{"$f":"IF(D17=0,0,IF(OR(F17=0,G17=0),1,0))","v":0},{"$f":"IF(G17=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G17)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G17=Lists!$G$6),AND('Section 2'!$L$13=0,G17=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G17=Lists!$G$3),AND('Section 2'!$G$13=0,G17=Lists!$G$4),AND('Section 2'!$H$13=0,G17=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D18=0,\"\",MAX($A$15:A17)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G18=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G18)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G18=Lists!$G$6),AND('Section 2'!$L$13=0,G18=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G18=Lists!$G$3),AND('Section 2'!$G$13=0,G18=Lists!$G$4),AND('Section 2'!$H$13=0,G18=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D19=0,\"\",MAX($A$15:A18)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G19=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G19)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G19=Lists!$G$6),AND('Section 2'!$L$13=0,G19=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G19=Lists!$G$3),AND('Section 2'!$G$13=0,G19=Lists!$G$4),AND('Section 2'!$H$13=0,G19=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D20=0,\"\",MAX($A$15:A19)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G20=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G20)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G20=Lists!$G$6),AND('Section 2'!$L$13=0,G20=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G20=Lists!$G$3),AND('Section 2'!$G$13=0,G20=Lists!$G$4),AND('Section 2'!$H$13=0,G20=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D21=0,\"\",MAX($A$15:A20)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G21=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G21)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G21=Lists!$G$6),AND('Section 2'!$L$13=0,G21=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G21=Lists!$G$3),AND('Section 2'!$G$13=0,G21=Lists!$G$4),AND('Section 2'!$H$13=0,G21=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D22=0,\"\",MAX($A$15:A21)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G22=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G22)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G22=Lists!$G$6),AND('Section 2'!$L$13=0,G22=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G22=Lists!$G$3),AND('Section 2'!$G$13=0,G22=Lists!$G$4),AND('Section 2'!$H$13=0,G22=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D23=0,\"\",MAX($A$15:A22)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G23=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G23)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G23=Lists!$G$6),AND('Section 2'!$L$13=0,G23=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G23=Lists!$G$3),AND('Section 2'!$G$13=0,G23=Lists!$G$4),AND('Section 2'!$H$13=0,G23=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D24=0,\"\",MAX($A$15:A23)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G24=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G24)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G24=Lists!$G$6),AND('Section 2'!$L$13=0,G24=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G24=Lists!$G$3),AND('Section 2'!$G$13=0,G24=Lists!$G$4),AND('Section 2'!$H$13=0,G24=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D25=0,\"\",MAX($A$15:A24)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,{"$f":"IF(D25=0,0,IF(OR(F25=0,G25=0),1,0))","v":0},{"$f":"IF(G25=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G25)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G25=Lists!$G$6),AND('Section 2'!$L$13=0,G25=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G25=Lists!$G$3),AND('Section 2'!$G$13=0,G25=Lists!$G$4),AND('Section 2'!$H$13=0,G25=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D26=0,\"\",MAX($A$15:A25)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G26=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G26)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G26=Lists!$G$6),AND('Section 2'!$L$13=0,G26=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G26=Lists!$G$3),AND('Section 2'!$G$13=0,G26=Lists!$G$4),AND('Section 2'!$H$13=0,G26=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D27=0,\"\",MAX($A$15:A26)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G27=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G27)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G27=Lists!$G$6),AND('Section 2'!$L$13=0,G27=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G27=Lists!$G$3),AND('Section 2'!$G$13=0,G27=Lists!$G$4),AND('Section 2'!$H$13=0,G27=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D28=0,\"\",MAX($A$15:A27)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G28=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G28)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G28=Lists!$G$6),AND('Section 2'!$L$13=0,G28=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G28=Lists!$G$3),AND('Section 2'!$G$13=0,G28=Lists!$G$4),AND('Section 2'!$H$13=0,G28=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D29=0,\"\",MAX($A$15:A28)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G29=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G29)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G29=Lists!$G$6),AND('Section 2'!$L$13=0,G29=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G29=Lists!$G$3),AND('Section 2'!$G$13=0,G29=Lists!$G$4),AND('Section 2'!$H$13=0,G29=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D30=0,\"\",MAX($A$15:A29)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G30=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G30)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G30=Lists!$G$6),AND('Section 2'!$L$13=0,G30=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G30=Lists!$G$3),AND('Section 2'!$G$13=0,G30=Lists!$G$4),AND('Section 2'!$H$13=0,G30=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D31=0,\"\",MAX($A$15:A30)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G31=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G31)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G31=Lists!$G$6),AND('Section 2'!$L$13=0,G31=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G31=Lists!$G$3),AND('Section 2'!$G$13=0,G31=Lists!$G$4),AND('Section 2'!$H$13=0,G31=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D32=0,\"\",MAX($A$15:A31)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G32=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G32)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G32=Lists!$G$6),AND('Section 2'!$L$13=0,G32=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G32=Lists!$G$3),AND('Section 2'!$G$13=0,G32=Lists!$G$4),AND('Section 2'!$H$13=0,G32=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D33=0,\"\",MAX($A$15:A32)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G33=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G33)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G33=Lists!$G$6),AND('Section 2'!$L$13=0,G33=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G33=Lists!$G$3),AND('Section 2'!$G$13=0,G33=Lists!$G$4),AND('Section 2'!$H$13=0,G33=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D34=0,\"\",MAX($A$15:A33)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G34=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G34)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G34=Lists!$G$6),AND('Section 2'!$L$13=0,G34=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G34=Lists!$G$3),AND('Section 2'!$G$13=0,G34=Lists!$G$4),AND('Section 2'!$H$13=0,G34=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D35=0,\"\",MAX($A$15:A34)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G35=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G35)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G35=Lists!$G$6),AND('Section 2'!$L$13=0,G35=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G35=Lists!$G$3),AND('Section 2'!$G$13=0,G35=Lists!$G$4),AND('Section 2'!$H$13=0,G35=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D36=0,\"\",MAX($A$15:A35)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G36=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G36)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G36=Lists!$G$6),AND('Section 2'!$L$13=0,G36=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G36=Lists!$G$3),AND('Section 2'!$G$13=0,G36=Lists!$G$4),AND('Section 2'!$H$13=0,G36=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D37=0,\"\",MAX($A$15:A36)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G37=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G37)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G37=Lists!$G$6),AND('Section 2'!$L$13=0,G37=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G37=Lists!$G$3),AND('Section 2'!$G$13=0,G37=Lists!$G$4),AND('Section 2'!$H$13=0,G37=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D38=0,\"\",MAX($A$15:A37)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G38=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G38)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G38=Lists!$G$6),AND('Section 2'!$L$13=0,G38=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G38=Lists!$G$3),AND('Section 2'!$G$13=0,G38=Lists!$G$4),AND('Section 2'!$H$13=0,G38=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D39=0,\"\",MAX($A$15:A38)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G39=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G39)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G39=Lists!$G$6),AND('Section 2'!$L$13=0,G39=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G39=Lists!$G$3),AND('Section 2'!$G$13=0,G39=Lists!$G$4),AND('Section 2'!$H$13=0,G39=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D40=0,\"\",MAX($A$15:A39)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G40=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G40)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G40=Lists!$G$6),AND('Section 2'!$L$13=0,G40=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G40=Lists!$G$3),AND('Section 2'!$G$13=0,G40=Lists!$G$4),AND('Section 2'!$H$13=0,G40=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D41=0,\"\",MAX($A$15:A40)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G41=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G41)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G41=Lists!$G$6),AND('Section 2'!$L$13=0,G41=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G41=Lists!$G$3),AND('Section 2'!$G$13=0,G41=Lists!$G$4),AND('Section 2'!$H$13=0,G41=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D42=0,\"\",MAX($A$15:A41)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G42=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G42)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G42=Lists!$G$6),AND('Section 2'!$L$13=0,G42=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G42=Lists!$G$3),AND('Section 2'!$G$13=0,G42=Lists!$G$4),AND('Section 2'!$H$13=0,G42=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D43=0,\"\",MAX($A$15:A42)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G43=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G43)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G43=Lists!$G$6),AND('Section 2'!$L$13=0,G43=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G43=Lists!$G$3),AND('Section 2'!$G$13=0,G43=Lists!$G$4),AND('Section 2'!$H$13=0,G43=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D44=0,\"\",MAX($A$15:A43)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G44=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G44)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G44=Lists!$G$6),AND('Section 2'!$L$13=0,G44=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G44=Lists!$G$3),AND('Section 2'!$G$13=0,G44=Lists!$G$4),AND('Section 2'!$H$13=0,G44=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D45=0,\"\",MAX($A$15:A44)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G45=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G45)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G45=Lists!$G$6),AND('Section 2'!$L$13=0,G45=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G45=Lists!$G$3),AND('Section 2'!$G$13=0,G45=Lists!$G$4),AND('Section 2'!$H$13=0,G45=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D46=0,\"\",MAX($A$15:A45)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G46=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G46)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G46=Lists!$G$6),AND('Section 2'!$L$13=0,G46=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G46=Lists!$G$3),AND('Section 2'!$G$13=0,G46=Lists!$G$4),AND('Section 2'!$H$13=0,G46=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D47=0,\"\",MAX($A$15:A46)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G47=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G47)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G47=Lists!$G$6),AND('Section 2'!$L$13=0,G47=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G47=Lists!$G$3),AND('Section 2'!$G$13=0,G47=Lists!$G$4),AND('Section 2'!$H$13=0,G47=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D48=0,\"\",MAX($A$15:A47)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G48=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G48)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G48=Lists!$G$6),AND('Section 2'!$L$13=0,G48=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G48=Lists!$G$3),AND('Section 2'!$G$13=0,G48=Lists!$G$4),AND('Section 2'!$H$13=0,G48=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D49=0,\"\",MAX($A$15:A48)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G49=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G49)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G49=Lists!$G$6),AND('Section 2'!$L$13=0,G49=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G49=Lists!$G$3),AND('Section 2'!$G$13=0,G49=Lists!$G$4),AND('Section 2'!$H$13=0,G49=Lists!$G$5)),1,0)","v":0},0]
[{"$f":"IF(D50=0,\"\",MAX($A$15:A49)+1)","v":""},null,null,null,null,null,null,null,null,null,null,"N",0,0,{"$f":"IF(G50=0,0,IF(COUNTIF(Lists!$G$3:$G$7,G50)>0,0,1))","v":0},{"$f":"IF(OR(AND('Section 2'!$M$13=0,G50=Lists!$G$6),AND('Section 2'!$L$13=0,G50=Lists!$G$7)),1,0)","v":0},{"$f":"IF(OR(AND('Section 2'!$E$13=0,G50=Lists!$G$3),AND('Section 2'!$G$13=0,G50=Lists!$G$4),AND('Section 2'!$H$13=0,G50=Lists!$G$5)),1,0)","v":0},0]
[null,null,null,null,null,null,"x"]
[null,null,null,null,null,null,{"$f":"Lists!G3","v":"Transformation"}]
[null,null,null,null,null,null,{"$f":"Lists!G4","v":"Destruction"}]
[null,null,null,null,null,null,{"$f":"Lists!G5","v":"QPS"}]
[null,null,null,null,null,null,{"$f":"Lists!G6","v":"Global Lab"}]
[null,null,null,null,null,null,{"$f":"Lists!G7","v":"Emergency Use"}]

{"sheet":"Section 4","index":4,"n_rows":17,"n_cols":13,"rows_kept":17,"cut":false,"hidden":true,"merged":[[15,3,15,4],[16,3,16,4],[11,3,11,7],[8,3,8,7],[12,3,12,4],[13,3,13,4],[14,3,14,4]]}
[]
[null,null,null,"U.S. Environmental Protection Agency"]
[null,null,null,"Methyl Bromide Producer Quarterly Report"]
[]
[null,null,null,"Company Name:",{"$f":"IF('Section 1'!D9=0,\"\",'Section 1'!D9)","v":""}]
[null,null,null,"Reporting Period:",{"$f":"IF(OR('Section 1'!D11=0,'Section 1'!D12=0),\"\",\"Quarter \"&'Section 1'!D12&\", \"&'Section 1'!D11)","v":""}]
[]
[null,null,null,"Section 4: Producers Critical Use Year-End Inventory (Quarter 4 Only)"]
[null,null,null,"Identify the amount of critical use methyl bromide held by your company at the end of the control period.",null,null,null,null,null,null,null,"Q4 Inventory Check","Q1-Q3 Completeness Check"]
[null,null,null,null,"  kg owned by reporting company",null,null,null,null,null,null,"IF(ReportQtr=4,IF(ISBLANK(D10),1,0),0)",{"$f":"IF(ReportQtr<4,IF(D10<>0,1,0),0)","v":0}]
[]
[null,null,null,"Identify the name(s) of company(s) for which critical use methyl bromide is being held by the reporting entity, and the associated amounts held for each (excluding end-users)."]
[null,null,null,"Company Name",null,"Pre-Plant ","Post-Harvest "]
[null,null,null,"Text",null,"kg","kg",null,null,null,"ActiveRow","Q4 Completeness Check","Q1-Q3 Completeness Check"]
[{"$f":"IF(D15=0,\"\",1)","v":""},null,null,null,null,null,null,null,null,null,{"$f":"IF(D15=\"\",\"N\",\"Y\")","v":"N"},{"$f":"IF(K15=\"y\",IF(AND(ISBLANK(F15),ISBLANK(G15)),1,0),0)","v":0},{"$f":"IF(ReportQtr<4,IF(OR(K15=\"Y\",F15>0,G15>0),1,0),0)","v":0}]
[{"$f":"IF(D16=0,\"\",MAX($A$15:A15)+1)","v":""},null,null,null,null,null,null,null,null,null,{"$f":"IF(D16=\"\",\"N\",\"Y\")","v":"N"},{"$f":"IF(K16=\"y\",IF(AND(ISBLANK(F16),ISBLANK(G16)),1,0),0)","v":0},{"$f":"IF(ReportQtr<4,IF(OR(K16=\"Y\",F16>0,G16>0),1,0),0)","v":0}]
[{"$f":"IF(D17=0,\"\",MAX($A$15:A16)+1)","v":""},null,null,null,null,null,null,null,null,null,{"$f":"IF(D17=\"\",\"N\",\"Y\")","v":"N"},{"$f":"IF(K17=\"y\",IF(AND(ISBLANK(F17),ISBLANK(G17)),1,0),0)","v":0},{"$f":"IF(ReportQtr<4,IF(OR(K17=\"Y\",F17>0,G17>0),1,0),0)","v":0}]

{"sheet":"Summary","index":5,"n_rows":12,"n_cols":6,"rows_kept":12,"cut":false,"hidden":true,"merged":[[8,3,8,5],[9,3,10,3],[9,4,9,5]]}
[]
[null,null,null,"U.S. Environmental Protection Agency"]
[null,null,null,"Methyl Bromide Producer Quarterly Report"]
[]
[null,null,null,"Company Name:",{"$f":"IF('Section 1'!D9=0,\"\",'Section 1'!D9)","v":""}]
[null,null,null,"Reporting Period:",{"$f":"IF(OR('Section 1'!D11=0,'Section 1'!D12=0),\"\",\"Quarter \"&'Section 1'!D12&\", \"&'Section 1'!D11)","v":""}]
[]
[null,null,null,"Allowance Summary"]
[null,null,null,"The values in the table below are calculated based on data entered in Section 2.  If the totals appear to be incorrect, please return to Section 2 to review your data."]
[null,null,null,"Chemical Name","Allowances Expended (kg)"]
[null,null,null,null,"Pre-Plant Critical Use","Post-Harvest Critical Use"]
[1,null,null,"CH3Br",{"$f":"'Section 2'!I13","v":0},{"$f":"'Section 2'!J13","v":0}]

{"sheet":"Checks","index":6,"n_rows":29,"n_cols":5,"rows_kept":29,"cut":false,"hidden":true,"merged":[]}
[]
[null,"Section","Check Description","Status (1 = Incomplete, 0 = Complete)"]
[null,"Section 1","All - Section 1",{"$f":"IF(SUM('Section 1'!F9:F12)>0,1,0)","v":1},"Stopper"]
[null,"Section 2","Negative Numbers?",{"$f":"'Section 2'!T13","v":0},"Stopper"]
[null,"Section 2","Error Check",{"$f":"D4","v":0},"Error Check"]
[null,"Section 2","Filled Out",{"$f":"IF('Section 2'!Q13=\"N\",1,0)","v":1},"Warning"]
[null,"Section 3","Section 3 Inclusion - Lab/Emergency",{"$f":"'Section 2'!S13","v":0},"Stopper"]
[null,"Section 3","Character Check",{"$f":"IF(SUM('Section 3'!M15:M24)>0,1,0)","v":0},"Stopper"]
[null,"Section 3","Sec 2 Inclusion - Lab/Emergency",{"$f":"IF(SUM('Section 3'!P15:P24)>0,1,0)","v":0},"Stopper"]
[null,"Section 3","Completeness check",{"$f":"IF(SUM('Section 3'!N15:N24)>0,1,0)","v":0},"Stopper"]
[null,"Section 3","Sec3 Valid Purpose",{"$f":"IF(SUM('Section 3'!O15:O24)>0,1,0)","v":0},"Stopper"]
[null,"Section 3","Negative Numbers?",{"$f":"IF(SUM('Section 3'!R15:R50)>0,1,0)","v":0},"Stopper"]
[null,"Section 3","Error Check",{"$f":"IF(SUM(D7:D12)>0,1,0)","v":0},"Error Check"]
[null,"Section 3","Sec2 Inclusion 2nd Party in Sec 3",{"$f":"'Section 2'!R13","v":0},"Warning"]
[null,"Section 3","Sec2 Inclusion 2nd Party in Sec3",{"$f":"IF(SUM('Section 3'!Q15:Q24)>0,1,0)","v":0},"Warning"]
[null,"Section 4","Q4 Completeness Check","IF(SUM('Section 4'!L15:L17)>0,1,0)","Stopper"]
[null,"Section 4","Q1-Q3 Completeness Check","IF(SUM('Section 4'!M15:M17,'Section 4'!M10)>0,1,0)","Stopper"]
[null,"Section 4","Q4 Inventory Check",{"$f":"'Section 4'!L10","v":"IF(ReportQtr=4,IF(ISBLANK(D10),1,0),0)"},"Stopper"]
[null,"Section 4","Error Check","IF(SUM(D14:D16)>0,1,0)","Error Check"]
[null,"All","Error Check",{"$f":"IF(SUM(Sec1Status,Sec2Error,Sec3Error,Sec4Error)>0,1,0)","v":1},"Error Check"]
[]
[]
[]
[]
[null,"Numerical Checks against Output for CSV"]
[null,"Section 2","Production (double counts with total",{"$f":"SUM('Section 2'!D13:N13)-SUM(OutputForCSV!E2:O2)","v":0}]
[null,"Section 3","Section 3 Quantity",{"$f":"SUMIF('Section 3'!L15:L24,\"Y\",'Section 3'!F15:F24)-SUM(OutputForCSV!F3:F12)","v":0}]
[null,"Section 4","Section 4 Quantities",{"$f":"SUMIF('Section 4'!K15:K17,\"Y\",'Section 4'!F15:F17)+SUMIF('Section 4'!K15:K17,\"Y\",'Section 4'!G15:G17)-SUM(OutputForCSV!E40:F42)","v":0}]
[null,"ALL","TOTAL",{"$f":"SUM(D26:D27)","v":0}]

{"sheet":"OutputForCSV","index":7,"n_rows":43,"n_cols":16,"rows_kept":43,"cut":false,"hidden":true,"merged":[]}
["Row #","Entry",1,"PROD3","4",{"$f":"'Section 1'!D5","v":"2020-07-15"},{"$f":"'Section 1'!D9","v":0},{"$f":"'Section 1'!D10","v":0},{"$f":"'Section 1'!D11","v":0},{"$f":"'Section 1'!D12","v":0},null,null,null,null,null,"LastColumn"]
[{"$f":"IF(D2=\"\",\"\",ROWS($A$1:A2))","v":""},1,{"$f":"IF(D2=\"\",\"\",2)","v":""},{"$f":"IF(O2=\"\",\"\",\"CH3Br\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:D$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:E$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:F$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:G$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:H$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:I$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:J$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:K$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:L$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:M$13),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$13:$N$13,COLUMNS('Section 2'!$A$13:N$13),0),\"\")","v":""}]
[{"$f":"IF(D3=\"\",\"\",ROWS($A$1:A3))","v":""},1,{"$f":"IF(D3=\"\",\"\",3)","v":""},{"$f":"IF(E3=\"\",\"\",\"CH3Br\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B3,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B3,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D4=\"\",\"\",ROWS($A$1:A4))","v":""},2,{"$f":"IF(D4=\"\",\"\",3)","v":""},{"$f":"IF(E4=\"\",\"\",\"CH3Br\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B4,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B4,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D5=\"\",\"\",ROWS($A$1:A5))","v":""},3,"","",{"$f":"IFERROR(VLOOKUP($B5,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B5,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B5,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B5,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D6=\"\",\"\",ROWS($A$1:A6))","v":""},4,"","",{"$f":"IFERROR(VLOOKUP($B6,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B6,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B6,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B6,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D7=\"\",\"\",ROWS($A$1:A7))","v":""},5,"","",{"$f":"IFERROR(VLOOKUP($B7,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B7,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B7,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B7,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D8=\"\",\"\",ROWS($A$1:A8))","v":""},6,"","",{"$f":"IFERROR(VLOOKUP($B8,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B8,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B8,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B8,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D9=\"\",\"\",ROWS($A$1:A9))","v":""},7,"","",{"$f":"IFERROR(VLOOKUP($B9,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B9,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B9,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B9,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D10=\"\",\"\",ROWS($A$1:A10))","v":""},8,"","",{"$f":"IFERROR(VLOOKUP($B10,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B10,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B10,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B10,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D11=\"\",\"\",ROWS($A$1:A11))","v":""},9,"","",{"$f":"IFERROR(VLOOKUP($B11,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B11,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B11,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B11,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D12=\"\",\"\",ROWS($A$1:A12))","v":""},10,"",{"$f":"IF(E12=\"\",\"\",\"CH3Br\")","v":""},{"$f":"IFERROR(VLOOKUP($B12,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B12,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B12,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B12,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D13=\"\",\"\",ROWS($A$1:A13))","v":""},11,"","",{"$f":"IFERROR(VLOOKUP($B13,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B13,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B13,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B13,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D14=\"\",\"\",ROWS($A$1:A14))","v":""},12,"","",{"$f":"IFERROR(VLOOKUP($B14,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B14,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B14,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B14,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D15=\"\",\"\",ROWS($A$1:A15))","v":""},13,"","",{"$f":"IFERROR(VLOOKUP($B15,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B15,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B15,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B15,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D16=\"\",\"\",ROWS($A$1:A16))","v":""},14,"","",{"$f":"IFERROR(VLOOKUP($B16,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B16,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B16,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B16,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D17=\"\",\"\",ROWS($A$1:A17))","v":""},15,"","",{"$f":"IFERROR(VLOOKUP($B17,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B17,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B17,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B17,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D18=\"\",\"\",ROWS($A$1:A18))","v":""},16,"","",{"$f":"IFERROR(VLOOKUP($B18,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B18,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B18,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B18,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D19=\"\",\"\",ROWS($A$1:A19))","v":""},17,"","",{"$f":"IFERROR(VLOOKUP($B19,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B19,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B19,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B19,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D20=\"\",\"\",ROWS($A$1:A20))","v":""},18,"","",{"$f":"IFERROR(VLOOKUP($B20,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B20,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B20,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B20,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D21=\"\",\"\",ROWS($A$1:A21))","v":""},19,"","",{"$f":"IFERROR(VLOOKUP($B21,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B21,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B21,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B21,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D22=\"\",\"\",ROWS($A$1:A22))","v":""},20,"","",{"$f":"IFERROR(VLOOKUP($B22,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B22,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B22,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B22,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D23=\"\",\"\",ROWS($A$1:A23))","v":""},21,"","",{"$f":"IFERROR(VLOOKUP($B23,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B23,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B23,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B23,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D24=\"\",\"\",ROWS($A$1:A24))","v":""},22,"","",{"$f":"IFERROR(VLOOKUP($B24,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B24,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B24,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B24,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D25=\"\",\"\",ROWS($A$1:A25))","v":""},23,"","",{"$f":"IFERROR(VLOOKUP($B25,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B25,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B25,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B25,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D26=\"\",\"\",ROWS($A$1:A26))","v":""},24,"","",{"$f":"IFERROR(VLOOKUP($B26,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B26,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B26,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B26,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D27=\"\",\"\",ROWS($A$1:A27))","v":""},25,"","",{"$f":"IFERROR(VLOOKUP($B27,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B27,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B27,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B27,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D28=\"\",\"\",ROWS($A$1:A28))","v":""},26,"","",{"$f":"IFERROR(VLOOKUP($B28,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B28,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B28,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B28,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D29=\"\",\"\",ROWS($A$1:A29))","v":""},27,"","",{"$f":"IFERROR(VLOOKUP($B29,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B29,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B29,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B29,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D30=\"\",\"\",ROWS($A$1:A30))","v":""},28,"","",{"$f":"IFERROR(VLOOKUP($B30,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B30,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B30,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B30,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D31=\"\",\"\",ROWS($A$1:A31))","v":""},29,"","",{"$f":"IFERROR(VLOOKUP($B31,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B31,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B31,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B31,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D32=\"\",\"\",ROWS($A$1:A32))","v":""},30,"","",{"$f":"IFERROR(VLOOKUP($B32,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B32,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B32,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B32,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D33=\"\",\"\",ROWS($A$1:A33))","v":""},31,"","",{"$f":"IFERROR(VLOOKUP($B33,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B33,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B33,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B33,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D34=\"\",\"\",ROWS($A$1:A34))","v":""},32,"","",{"$f":"IFERROR(VLOOKUP($B34,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B34,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B34,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B34,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D35=\"\",\"\",ROWS($A$1:A35))","v":""},33,"","",{"$f":"IFERROR(VLOOKUP($B35,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B35,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B35,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B35,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D36=\"\",\"\",ROWS($A$1:A36))","v":""},34,"","",{"$f":"IFERROR(VLOOKUP($B36,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B36,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B36,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B36,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D37=\"\",\"\",ROWS($A$1:A37))","v":""},35,"","",{"$f":"IFERROR(VLOOKUP($B37,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B37,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B37,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B37,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D38=\"\",\"\",ROWS($A$1:A38))","v":""},36,"","",{"$f":"IFERROR(VLOOKUP($B38,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:D$15),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B38,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:F$15),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B38,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$15),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B38,'Section 3'!$A$15:$G$50,COLUMNS('Section 3'!$A$15:G$50),0))),\"\")","v":""}]
[{"$f":"IF(D39=\"\",\"\",ROWS($A$1:A39))","v":""},null,{"$f":"IF(D39=\"\",\"\",\"4a\")","v":""},{"$f":"IF(ISBLANK('Section 4'!D10),\"\",'Section 4'!D10)","v":""}]
[{"$f":"IF(D40=\"\",\"\",ROWS($A$1:A40))","v":""},1,{"$f":"IF(D40=\"\",\"\",\"4b\")","v":""},{"$f":"IFERROR(VLOOKUP($B40,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:D$17),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B40,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:F$17),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B40,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:G$17),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B40,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:G$17),0))),\"\")","v":""}]
[{"$f":"IF(D41=\"\",\"\",ROWS($A$1:A41))","v":""},2,{"$f":"IF(D41=\"\",\"\",\"4b\")","v":""},{"$f":"IFERROR(VLOOKUP($B41,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:D$17),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B41,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:F$17),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B41,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:G$17),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B41,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:G$17),0))),\"\")","v":""}]
[{"$f":"IF(D42=\"\",\"\",ROWS($A$1:A42))","v":""},3,{"$f":"IF(D42=\"\",\"\",\"4b\")","v":""},{"$f":"IFERROR(VLOOKUP($B42,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:D$17),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B42,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:F$17),0),\"\")","v":""},{"$f":"IFERROR(IF(VLOOKUP($B42,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:G$17),0)=\"QPS\",\"QPS\",PROPER(VLOOKUP($B42,'Section 4'!$A$15:$G$17,COLUMNS('Section 4'!$A$15:G$17),0))),\"\")","v":""}]
[null,"LastRow"]

{"sheet":"Lists","index":8,"n_rows":31,"n_cols":21,"rows_kept":31,"cut":false,"hidden":true,"merged":[]}
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Variables for Data Submission"]
[null,"Chemical Name","Submission Type","Reporting Year","Current Year","Reporting Quarter","Purpose","Date for CSV Title","Form Name for CSV Title",null,"Incorrect Capitalizations","Correct Spelling",null,"Invalid Character","Replacement Character",null,"Form Type","Form Code",null,null,"Row #"]
[null,"CH3Br","Original Submission",2018,{"$f":"YEAR(TODAY())","v":2020},1,"Transformation",{"$f":"MONTH(SubDate)&\"-\"&DAY(SubDate)&\"-\"&YEAR(SubDate)","v":"7-15-2020"},"MeBr Producer",null,"cfc","CFC",null,"À","A",null,"Class I Producer","PROD1",null,"Sec2End",{"$f":"IF(MAX(OutputForCSV!A2:A2)=0,1,MAX(OutputForCSV!A2:A2))","v":1}]
[null,null,"Re-Submittal",2019,null,2,"Destruction",null,null,null,"CCl4","CCL4",null,"Á","A",null,"MeBr Producer","PROD3",null,"Sec3Start",{"$f":"OutputForCSV!A3","v":""}]
[null,null,null,2020,null,3,"QPS",null,null,null,"cbm","CBM",null,"Ã","A",null,"Class II Producer","PROD2",null,"Sec3End",{"$f":"MAX(OutputForCSV!A3:A38)","v":0}]
[null,null,null,2021,null,4,"Global Lab",null,null,null,"HBFCS","HBFCs",null,"Ä","A",null,"Class I Importer","IMPT1",null,"Sec4Start",{"$f":"OutputForCSV!A39","v":""}]
[null,null,null,2022,null,null,"Emergency Use",null,null,null,"ch3ccl3","CH3CCL3",null,"Â","A",null,"MeBr Importer","IMPT3",null,"Sec4End",{"$f":"MAX(OutputForCSV!A39:A42)","v":0}]
[null,null,null,2023,null,null,null,null,null,null,"CH3BR","CH3Br",null,"Å","A",null,"Class II Importer","IMPT2",null,"MaxTempRow",{"$f":"IF(MAX(TempOutput!A2:A40)=0,1,MAX(TempOutput!A2:A40))","v":3}]
[null,null,null,2024,null,null,null,null,null,null,"HALON","Halon",null,"È","E",null,"Class I Exporter","EXPT1",null,"Sec3PasteRow",{"$f":"IF(U3=0,2,U3+1)","v":2}]
[null,null,null,2025,null,null,null,null,null,null,null,null,null,"É","E",null,"MeBr Exporter","EXPT3",null,"Sec4PasteRow",{"$f":"ROWS(OutputForCSV!A1:A38)-COUNTIF(OutputForCSV!A2:A38,\"\")+1","v":2}]
[null,null,null,2026,null,null,null,null,null,null,null,null,null,"Ê","E",null,"Class II Exporter","EXPT2"]
[null,null,null,2027,null,null,null,null,null,null,null,null,null,"Ë","E",null,"Class I Lab Supplier","LABS1"]
[null,null,null,2028,null,null,null,null,null,null,null,null,null,"Ì","I",null,"Class I Destruction","DEST1"]
[null,null,null,2029,null,null,null,null,null,null,null,null,null,"Í","I",null,"MeBr Destruction","DEST3"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Í","I",null,"Class II Destruction","DEST2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ï","I",null,"Class I Transformation","TRAN1"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ò","O",null,"MeBr Transformation","TRAN3"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ó","O",null,"Class II Transformation","TRAN2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ô","O",null,"MeBr Trades","TRAD3"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ö","O",null,"Class II Trades","TRAD2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Õ","O",null,"Class II RACA","RACA2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ù","U",null,"MeBr Distributor of QPS","MBQPS"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ú","U",null,"MeBr Pre-2005 Stocks","MB05S"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Û","U",null,"MeBr Sales of CU","MBCUE"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ü","U",null,"Petitions","PETIT"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ç","C"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"Ñ","N"]
[null,null,null,null,null,null,null,null,null,null,null,null,null," "," "]
[null,null,null,null,null,null,null,null,null,null,null,null,null," "," "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"–"," "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,"—"," "]

{"sheet":"TempOutput","index":9,"n_rows":40,"n_cols":14,"rows_kept":40,"cut":false,"hidden":true,"merged":[]}
["MaxRow",1,"PROD3","4","2020-06-23","blah","Original Submission",2019,1]
[{"$f":"IF(OR(B2=\"\",B2=0),\"\",ROWS($A$1:A2))","v":2},2,"CH3Br",1,1,0,0,0,0,0,0,0,0,2]
[{"$f":"IF(OR(B3=\"\",B3=0),\"\",ROWS($A$1:A3))","v":3},3,"CH3Br","Company ñ",1,"Transformation"]
[{"$f":"IF(OR(B4=\"\",B4=0),\"\",ROWS($A$1:A4))","v":""}]
[{"$f":"IF(OR(B5=\"\",B5=0),\"\",ROWS($A$1:A5))","v":""}]
[{"$f":"IF(OR(B6=\"\",B6=0),\"\",ROWS($A$1:A6))","v":""}]
[{"$f":"IF(OR(B7=\"\",B7=0),\"\",ROWS($A$1:A7))","v":""}]
[{"$f":"IF(OR(B8=\"\",B8=0),\"\",ROWS($A$1:A8))","v":""}]
[{"$f":"IF(OR(B9=\"\",B9=0),\"\",ROWS($A$1:A9))","v":""}]
[{"$f":"IF(OR(B10=\"\",B10=0),\"\",ROWS($A$1:A10))","v":""}]
[{"$f":"IF(OR(B11=\"\",B11=0),\"\",ROWS($A$1:A11))","v":""}]
[{"$f":"IF(OR(B12=\"\",B12=0),\"\",ROWS($A$1:A12))","v":""}]
[{"$f":"IF(OR(B13=\"\",B13=0),\"\",ROWS($A$1:A13))","v":""}]
[{"$f":"IF(OR(B14=\"\",B14=0),\"\",ROWS($A$1:A14))","v":""}]
[{"$f":"IF(OR(B15=\"\",B15=0),\"\",ROWS($A$1:A15))","v":""}]
[{"$f":"IF(OR(B16=\"\",B16=0),\"\",ROWS($A$1:A16))","v":""}]
[{"$f":"IF(OR(B17=\"\",B17=0),\"\",ROWS($A$1:A17))","v":""}]
[{"$f":"IF(OR(B18=\"\",B18=0),\"\",ROWS($A$1:A18))","v":""}]
[{"$f":"IF(OR(B19=\"\",B19=0),\"\",ROWS($A$1:A19))","v":""}]
[{"$f":"IF(OR(B20=\"\",B20=0),\"\",ROWS($A$1:A20))","v":""}]
[{"$f":"IF(OR(B21=\"\",B21=0),\"\",ROWS($A$1:A21))","v":""}]
[{"$f":"IF(OR(B22=\"\",B22=0),\"\",ROWS($A$1:A22))","v":""}]
[{"$f":"IF(OR(B23=\"\",B23=0),\"\",ROWS($A$1:A23))","v":""}]
[{"$f":"IF(OR(B24=\"\",B24=0),\"\",ROWS($A$1:A24))","v":""}]
[{"$f":"IF(OR(B25=\"\",B25=0),\"\",ROWS($A$1:A25))","v":""}]
[{"$f":"IF(OR(B26=\"\",B26=0),\"\",ROWS($A$1:A26))","v":""}]
[{"$f":"IF(OR(B27=\"\",B27=0),\"\",ROWS($A$1:A27))","v":""}]
[{"$f":"IF(OR(B28=\"\",B28=0),\"\",ROWS($A$1:A28))","v":""}]
[{"$f":"IF(OR(B29=\"\",B29=0),\"\",ROWS($A$1:A29))","v":""}]
[{"$f":"IF(OR(B30=\"\",B30=0),\"\",ROWS($A$1:A30))","v":""}]
[{"$f":"IF(OR(B31=\"\",B31=0),\"\",ROWS($A$1:A31))","v":""}]
[{"$f":"IF(OR(B32=\"\",B32=0),\"\",ROWS($A$1:A32))","v":""}]
[{"$f":"IF(OR(B33=\"\",B33=0),\"\",ROWS($A$1:A33))","v":""}]
[{"$f":"IF(OR(B34=\"\",B34=0),\"\",ROWS($A$1:A34))","v":""}]
[{"$f":"IF(OR(B35=\"\",B35=0),\"\",ROWS($A$1:A35))","v":""}]
[{"$f":"IF(OR(B36=\"\",B36=0),\"\",ROWS($A$1:A36))","v":""}]
[{"$f":"IF(OR(B37=\"\",B37=0),\"\",ROWS($A$1:A37))","v":""}]
[{"$f":"IF(OR(B38=\"\",B38=0),\"\",ROWS($A$1:A38))","v":""}]
[{"$f":"IF(OR(B39=\"\",B39=0),\"\",ROWS($A$1:A39))","v":""}]
[{"$f":"IF(OR(B40=\"\",B40=0),\"\",ROWS($A$1:A40))","v":""}]